{"id":403,"date":"2023-06-19T10:38:24","date_gmt":"2023-06-19T10:38:24","guid":{"rendered":"https:\/\/physigeek.com\/pt\/forca-centripeta\/"},"modified":"2023-06-19T10:38:24","modified_gmt":"2023-06-19T10:38:24","slug":"forca-centripeta","status":"publish","type":"post","link":"https:\/\/physigeek.com\/pt\/forca-centripeta\/","title":{"rendered":"For\u00e7a centr\u00edpeta"},"content":{"rendered":"<p>Este artigo explica o que \u00e9 for\u00e7a centr\u00edpeta na f\u00edsica. Assim voc\u00ea aprender\u00e1 o significado da for\u00e7a centr\u00edpeta, como calcular a for\u00e7a centr\u00edpeta e, al\u00e9m disso, um exerc\u00edcio resolvido passo a passo. <\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue-es-la-fuerza-centripeta\"><\/span> O que \u00e9 for\u00e7a centr\u00edpeta?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p> <strong>A for\u00e7a centr\u00edpeta<\/strong> \u00e9 uma for\u00e7a que atua sobre um corpo que descreve um <a href=\"https:\/\/physigeek.com\/pt\/movimento-circular\/\">movimento circular<\/a> . Mais especificamente, a for\u00e7a centr\u00edpeta \u00e9 a for\u00e7a que faz com que o corpo mude de dire\u00e7\u00e3o e, portanto, trace uma trajet\u00f3ria circular. A for\u00e7a centr\u00edpeta, portanto, s\u00f3 aparece em movimentos circulares.<\/p>\n<p> Por exemplo, se prendermos um barbante a uma bola e gir\u00e1-la em torno de um eixo a uma velocidade constante, a bola seguir\u00e1 uma trajet\u00f3ria circular porque o barbante exerce uma for\u00e7a centr\u00edpeta sobre ela. Outro exemplo de for\u00e7a centr\u00edpeta \u00e9 a for\u00e7a que mant\u00e9m um sat\u00e9lite em \u00f3rbita.<\/p>\n<p> A principal caracter\u00edstica da for\u00e7a centr\u00edpeta \u00e9 que ela \u00e9 perpendicular \u00e0 velocidade do corpo que descreve o movimento circular, que \u00e9 tangente \u00e0 trajet\u00f3ria circular. Portanto, a for\u00e7a centr\u00edpeta aponta sempre para o centro do movimento circular. <\/p>\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/force-centripete-et-force-tangentielle.png\" alt=\"for\u00e7a centr\u00edpeta e for\u00e7a tangencial\" class=\"wp-image-7626\" width=\"165\" height=\"205\"><\/figure>\n<p> Como voc\u00ea pode ver na imagem anterior, a dire\u00e7\u00e3o da for\u00e7a centr\u00edpeta (F <sub>c<\/sub> ) \u00e9 radial e sua dire\u00e7\u00e3o \u00e9 em dire\u00e7\u00e3o ao centro da trajet\u00f3ria circular. Por outro lado, a for\u00e7a tangencial (F <sub>t<\/sub> ) \u00e9 perpendicular \u00e0 for\u00e7a centr\u00edpeta e tamb\u00e9m aparece em certos tipos de movimentos circulares. A seguir veremos quais s\u00e3o as diferen\u00e7as entre for\u00e7a centr\u00edpeta e for\u00e7a tangencial. <\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Formula-de-la-fuerza-centripeta\"><\/span> F\u00f3rmula de for\u00e7a centr\u00edpeta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p> A for\u00e7a centr\u00edpeta \u00e9 igual \u00e0 massa do corpo vezes a <a href=\"https:\/\/physigeek.com\/pt\/aceleracao-centripeta-ou-aceleracao-normal\/\">acelera\u00e7\u00e3o centr\u00edpeta<\/a> . A for\u00e7a centr\u00edpeta \u00e9, portanto, igual \u00e0 massa do corpo multiplicada pelo quadrado da velocidade dividido pelo raio. A for\u00e7a centr\u00edpeta tamb\u00e9m \u00e9 calculada multiplicando a massa pelo quadrado da velocidade angular pelo raio.<\/p>\n<p> Resumindo, a <strong>f\u00f3rmula para calcular a for\u00e7a centr\u00edpeta<\/strong> \u00e9: <\/p>\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/formule-de-la-force-centripete.png\" alt=\"f\u00f3rmula da for\u00e7a centr\u00edpeta\" class=\"wp-image-7629\" width=\"234\" height=\"234\" srcset=\"https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/formule-de-la-force-centripete-300x300.png 300w, https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/formule-de-la-force-centripete-150x150.png 150w, https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/formule-de-la-force-centripete.png 431w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/figure>\n<p style=\"margin-bottom:5px\"> Ouro: <\/p>\n<ul style=\"color:#4fd12f; font-weight: bold;\">\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-b7e95e71f7ef52482db0a2a51d4643fb_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"F_c\" title=\"Rendered by QuickLaTeX.com\" height=\"15\" width=\"17\" style=\"vertical-align: -3px;\"><\/p>\n<p> \u00e9 a acelera\u00e7\u00e3o centr\u00edpeta. <\/span><\/li>\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-fdc40b8ad1cdad0aab9d632215459d28_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"m\" title=\"Rendered by QuickLaTeX.com\" height=\"8\" width=\"15\" style=\"vertical-align: 0px;\"><\/p>\n<p> \u00e9 a massa do corpo em movimento que realiza o movimento circular. <\/span><\/li>\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-34507a55d19314330bf60a03e52dc3b1_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"a_c\" title=\"Rendered by QuickLaTeX.com\" height=\"11\" width=\"15\" style=\"vertical-align: -3px;\"><\/p>\n<p> \u00e9 a acelera\u00e7\u00e3o centr\u00edpeta (ou acelera\u00e7\u00e3o normal). <\/span><\/li>\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-796872219106704832bd95ce08640b7b_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"v\" title=\"Rendered by QuickLaTeX.com\" height=\"8\" width=\"9\" style=\"vertical-align: 0px;\"><\/p>\n<p> \u00e9 a velocidade tangencial (ou velocidade linear). <\/span><\/li>\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-01bcf7e9e043561da78fecf715c8a46e_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"r\" title=\"Rendered by QuickLaTeX.com\" height=\"8\" width=\"8\" style=\"vertical-align: 0px;\"><\/p>\n<p> \u00e9 o raio da trajet\u00f3ria do movimento circular. <\/span><\/li>\n<li style=\"margin-bottom:5px\"><span style=\"color:#101010;font-weight: normal;\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-fbffdce91996e0a17795d82e8e6996d9_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"\\omega\" title=\"Rendered by QuickLaTeX.com\" height=\"8\" width=\"11\" style=\"vertical-align: 0px;\"><\/p>\n<p> \u00e9 a velocidade angular.<\/span><\/li>\n<\/ul>\n<p> Observe que a for\u00e7a centr\u00edpeta sempre aponta para o centro da trajet\u00f3ria circular. O sinal da for\u00e7a centr\u00edpeta ser\u00e1, portanto, positivo ou negativo dependendo do sistema de refer\u00eancia escolhido. <\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ejemplo-del-calculo-de-la-fuerza-centripeta\"><\/span> Exemplo de c\u00e1lculo de for\u00e7a centr\u00edpeta<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p> Agora que sabemos a defini\u00e7\u00e3o de for\u00e7a centr\u00edpeta e qual \u00e9 sua f\u00f3rmula, vamos ver um exemplo concreto de como esse tipo de for\u00e7a \u00e9 calculado.<\/p>\n<ul>\n<li> Um corpo em movimento de massa m = 8 kg descreve um <a href=\"https:\/\/physigeek.com\/pt\/movimento-circular-uniforme-mcu\/\">movimento circular uniforme<\/a> com velocidade angular de 2 rad\/s e raio de curvatura de 3 m. Qual \u00e9 a for\u00e7a centr\u00edpeta que atua sobre o corpo em movimento?<\/li>\n<\/ul>\n<p> Como o problema nos d\u00e1 o valor da velocidade angular do corpo, para encontrar a for\u00e7a centr\u00edpeta devemos utilizar a seguinte f\u00f3rmula:<\/p>\n<p class=\"has-text-align-center\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-ee2886fd0c5387c74af513de27065b7f_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"F_c=m\\cdot \\omega^2 \\cdot r\" title=\"Rendered by QuickLaTeX.com\" height=\"18\" width=\"110\" style=\"vertical-align: -3px;\"><\/p>\n<\/p>\n<p> Ent\u00e3o substitu\u00edmos os dados na f\u00f3rmula e calculamos a for\u00e7a centr\u00edpeta que atua sobre o corpo girat\u00f3rio realizando movimento circular uniforme: <\/p>\n<p class=\"has-text-align-center\">\n<p class=\"has-text-align-center\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/physigeek.com\/wp-content\/ql-cache\/quicklatex.com-bc297191d34cebe4900e157081f5679a_l3.png\" class=\"ql-img-inline-formula quicklatex-auto-format\" alt=\"F_c=8\\cdot 2^2 \\cdot 3= 96\\ N\" title=\"Rendered by QuickLaTeX.com\" height=\"18\" width=\"165\" style=\"vertical-align: -3px;\"><\/p>\n<\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Fuerza-centripeta-y-fuerza-tangencial\"><\/span> For\u00e7a centr\u00edpeta e for\u00e7a tangencial<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p> Nesta se\u00e7\u00e3o veremos qual \u00e9 a diferen\u00e7a entre for\u00e7a centr\u00edpeta e for\u00e7a tangencial, uma vez que estes s\u00e3o os dois principais tipos de for\u00e7as que aparecem em movimentos circulares variados.<\/p>\n<p> A <strong>for\u00e7a tangencial<\/strong> \u00e9 uma for\u00e7a que atua sobre um corpo que descreve um movimento circular n\u00e3o uniforme e \u00e9 tangencial \u00e0 trajet\u00f3ria seguida pelo corpo. For\u00e7a tangencial \u00e9 a for\u00e7a que faz com que o corpo gire mais r\u00e1pido ou mais devagar.<\/p>\n<p> A <strong>diferen\u00e7a entre a for\u00e7a centr\u00edpeta e a for\u00e7a tangencial<\/strong> \u00e9 que a for\u00e7a centr\u00edpeta causa uma mudan\u00e7a na dire\u00e7\u00e3o da trajet\u00f3ria do corpo em movimento, enquanto a for\u00e7a tangencial causa uma mudan\u00e7a na magnitude da velocidade do corpo.<\/p>\n<p> Al\u00e9m disso, a for\u00e7a centr\u00edpeta aponta para o centro da trajet\u00f3ria circular, enquanto a for\u00e7a tangencial \u00e9 tangente \u00e0 trajet\u00f3ria. A for\u00e7a centr\u00edpeta e a for\u00e7a tangencial s\u00e3o, portanto, perpendiculares.<\/p>\n<p> Tenha em mente que a for\u00e7a centr\u00edpeta existe em qualquer tipo de movimento circular, caso contr\u00e1rio o corpo em movimento seguiria uma trajet\u00f3ria reta. No entanto, a for\u00e7a tangencial \u00e9 zero no movimento circular uniforme porque a velocidade tangencial \u00e9 constante. <\/p>\n<div style=\"background-color:#FFFDE7; padding-top: 10px; padding-bottom: 10px; padding-right: 10px; padding-left: 20px; border: 2.5px dashed #FFB74D; border-radius:20px;\"> <span style=\"color:#ff951b\">\u27a4<\/span> <strong>Veja:<\/strong> <a href=\"https:\/\/physigeek.com\/pt\/forca-tangencial\/\">O que \u00e9 for\u00e7a tangencial?<\/a> <\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Fuerza-centripeta-y-fuerza-centrifuga\"><\/span> For\u00e7a centr\u00edpeta e for\u00e7a centr\u00edfuga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p> Por fim, veremos qual \u00e9 a diferen\u00e7a entre for\u00e7a centr\u00edpeta e for\u00e7a centr\u00edfuga, pois s\u00e3o dois tipos diferentes de for\u00e7as que muitas vezes s\u00e3o confundidas.<\/p>\n<p> <strong>A for\u00e7a centr\u00edfuga<\/strong> \u00e9 uma for\u00e7a fict\u00edcia que aparece ao estudar o movimento de um corpo a partir de um sistema de refer\u00eancia rotativo.<\/p>\n<p> Portanto, a <strong>diferen\u00e7a entre a for\u00e7a centr\u00edpeta e a for\u00e7a centr\u00edfuga<\/strong> \u00e9 que a for\u00e7a centr\u00edpeta \u00e9 uma for\u00e7a real que aparece quando um corpo faz um movimento circular, enquanto a for\u00e7a centr\u00edfuga \u00e9 uma for\u00e7a fict\u00edcia que aparece quando o referencial gira em um eixo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este artigo explica o que \u00e9 for\u00e7a centr\u00edpeta na f\u00edsica. Assim voc\u00ea aprender\u00e1 o significado da for\u00e7a centr\u00edpeta, como calcular a for\u00e7a centr\u00edpeta e, al\u00e9m disso, um exerc\u00edcio resolvido passo a passo. O que \u00e9 for\u00e7a centr\u00edpeta? A for\u00e7a centr\u00edpeta \u00e9 uma for\u00e7a que atua sobre um corpo que descreve um movimento circular . Mais &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\"> <span class=\"screen-reader-text\">For\u00e7a centr\u00edpeta<\/span> Leia mais &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-403","post","type-post","status-publish","format-standard","hentry","category-cinematografico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)<\/title>\n<meta name=\"description\" content=\"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)\" \/>\n<meta property=\"og:description\" content=\"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-19T10:38:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/force-centripete-et-force-tangentielle.png\" \/>\n<meta name=\"author\" content=\"Jonathan Reynolds\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jonathan Reynolds\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\"},\"author\":{\"name\":\"Jonathan Reynolds\",\"@id\":\"https:\/\/physigeek.com\/pt\/#\/schema\/person\/dbb0dcefd6128273c4dc80a663ede0f7\"},\"headline\":\"For\u00e7a centr\u00edpeta\",\"datePublished\":\"2023-06-19T10:38:24+00:00\",\"dateModified\":\"2023-06-19T10:38:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\"},\"wordCount\":901,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/physigeek.com\/pt\/#organization\"},\"articleSection\":[\"Cinematogr\u00e1fico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/physigeek.com\/pt\/forca-centripeta\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\",\"url\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\",\"name\":\"\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)\",\"isPartOf\":{\"@id\":\"https:\/\/physigeek.com\/pt\/#website\"},\"datePublished\":\"2023-06-19T10:38:24+00:00\",\"dateModified\":\"2023-06-19T10:38:24+00:00\",\"description\":\"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.\",\"breadcrumb\":{\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/physigeek.com\/pt\/forca-centripeta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/physigeek.com\/pt\/forca-centripeta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Lar\",\"item\":\"https:\/\/physigeek.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For\u00e7a centr\u00edpeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/physigeek.com\/pt\/#website\",\"url\":\"https:\/\/physigeek.com\/pt\/\",\"name\":\"Physigeek\",\"description\":\"Aprenda f\u00edsica da maneira mais f\u00e1cil!\",\"publisher\":{\"@id\":\"https:\/\/physigeek.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/physigeek.com\/pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/physigeek.com\/pt\/#organization\",\"name\":\"Physigeek\",\"url\":\"https:\/\/physigeek.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/physigeek.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/physigeek-logo.png\",\"contentUrl\":\"https:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/physigeek-logo.png\",\"width\":180,\"height\":42,\"caption\":\"Physigeek\"},\"image\":{\"@id\":\"https:\/\/physigeek.com\/pt\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/physigeek.com\/pt\/#\/schema\/person\/dbb0dcefd6128273c4dc80a663ede0f7\",\"name\":\"Jonathan Reynolds\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/physigeek.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/Jonathan-Reynolds-96x96.jpg\",\"contentUrl\":\"http:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/Jonathan-Reynolds-96x96.jpg\",\"caption\":\"Jonathan Reynolds\"},\"sameAs\":[\"http:\/\/physigeek.com\/pt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)","description":"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/physigeek.com\/pt\/forca-centripeta\/","og_locale":"pt_BR","og_type":"article","og_title":"\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)","og_description":"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.","og_url":"https:\/\/physigeek.com\/pt\/forca-centripeta\/","article_published_time":"2023-06-19T10:38:24+00:00","og_image":[{"url":"https:\/\/physigeek.com\/wp-content\/uploads\/2023\/09\/force-centripete-et-force-tangentielle.png"}],"author":"Jonathan Reynolds","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jonathan Reynolds","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/#article","isPartOf":{"@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/"},"author":{"name":"Jonathan Reynolds","@id":"https:\/\/physigeek.com\/pt\/#\/schema\/person\/dbb0dcefd6128273c4dc80a663ede0f7"},"headline":"For\u00e7a centr\u00edpeta","datePublished":"2023-06-19T10:38:24+00:00","dateModified":"2023-06-19T10:38:24+00:00","mainEntityOfPage":{"@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/"},"wordCount":901,"commentCount":0,"publisher":{"@id":"https:\/\/physigeek.com\/pt\/#organization"},"articleSection":["Cinematogr\u00e1fico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/physigeek.com\/pt\/forca-centripeta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/","url":"https:\/\/physigeek.com\/pt\/forca-centripeta\/","name":"\u25b7 O que \u00e9 for\u00e7a centr\u00edpeta? (f\u00f3rmula e exemplos)","isPartOf":{"@id":"https:\/\/physigeek.com\/pt\/#website"},"datePublished":"2023-06-19T10:38:24+00:00","dateModified":"2023-06-19T10:38:24+00:00","description":"Aqui voc\u00ea encontrar\u00e1 o que \u00e9 for\u00e7a centr\u00edpeta, como a for\u00e7a centr\u00edpeta \u00e9 calculada (f\u00f3rmula) e exemplos resolvidos de for\u00e7a centr\u00edpeta.","breadcrumb":{"@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/physigeek.com\/pt\/forca-centripeta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/physigeek.com\/pt\/forca-centripeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Lar","item":"https:\/\/physigeek.com\/pt\/"},{"@type":"ListItem","position":2,"name":"For\u00e7a centr\u00edpeta"}]},{"@type":"WebSite","@id":"https:\/\/physigeek.com\/pt\/#website","url":"https:\/\/physigeek.com\/pt\/","name":"Physigeek","description":"Aprenda f\u00edsica da maneira mais f\u00e1cil!","publisher":{"@id":"https:\/\/physigeek.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/physigeek.com\/pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/physigeek.com\/pt\/#organization","name":"Physigeek","url":"https:\/\/physigeek.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/physigeek.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/physigeek-logo.png","contentUrl":"https:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/physigeek-logo.png","width":180,"height":42,"caption":"Physigeek"},"image":{"@id":"https:\/\/physigeek.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/physigeek.com\/pt\/#\/schema\/person\/dbb0dcefd6128273c4dc80a663ede0f7","name":"Jonathan Reynolds","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/physigeek.com\/pt\/#\/schema\/person\/image\/","url":"http:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/Jonathan-Reynolds-96x96.jpg","contentUrl":"http:\/\/physigeek.com\/pt\/wp-content\/uploads\/2023\/10\/Jonathan-Reynolds-96x96.jpg","caption":"Jonathan Reynolds"},"sameAs":["http:\/\/physigeek.com\/pt"]}]}},"yoast_meta":{"yoast_wpseo_title":"","yoast_wpseo_metadesc":"","yoast_wpseo_canonical":""},"_links":{"self":[{"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/posts\/403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/comments?post=403"}],"version-history":[{"count":0,"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/posts\/403\/revisions"}],"wp:attachment":[{"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/media?parent=403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/categories?post=403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/physigeek.com\/pt\/wp-json\/wp\/v2\/tags?post=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}